
{"id":123073,"date":"2022-05-05T12:21:25","date_gmt":"2022-05-05T10:21:25","guid":{"rendered":"http:\/\/eafp.uvigo.gal\/gl\/?p=123073"},"modified":"2022-05-05T12:21:25","modified_gmt":"2022-05-05T10:21:25","slug":"continuaremos-o-noso-traballo-seguindo-o-ronsel-que-manolo-ramos-nos-debuxou","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/continuaremos-o-noso-traballo-seguindo-o-ronsel-que-manolo-ramos-nos-debuxou\/","title":{"rendered":"Continuaremos o noso traballo seguindo o ronsel que Manolo Ramos nos debuxou."},"content":{"rendered":"<p>Hoxe as bandeiras da nosa casa, ondean a media hasta, para despedir ao noso compa\u00f1eiro e amigo o vicerreitor Manolo Ramos.<\/p>\n<p>Manolo Ramos creou e impulsou a Escola Aberta co obxectivo de coordinar toda a oferta de formaci\u00f3n permanente da Universidade de Vigo. A s\u00faa visi\u00f3n da sociedade e da educaci\u00f3n seguir\u00e1 sempre connosco, deixounos unha pegada indeleble. Continuamos o noso traballo seguindo o ronsel que el nos debuxou.<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.uvigo.gal\/universidade\/comunicacion\/duvi\/fondo-pesar-comunidade-universitaria-falecemento-vicerreitor-manuel-ramos-cabrer\">DUVI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoxe as bandeiras da nosa casa, ondean a media hasta, para despedir ao noso compa\u00f1eiro e amigo o vicerreitor Manolo Ramos. Manolo Ramos creou e &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/continuaremos-o-noso-traballo-seguindo-o-ronsel-que-manolo-ramos-nos-debuxou\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":13,"featured_media":123077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-123073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/123073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=123073"}],"version-history":[{"count":1,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/123073\/revisions"}],"predecessor-version":[{"id":123080,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/123073\/revisions\/123080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/123077"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=123073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=123073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=123073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}