
{"id":136795,"date":"2023-05-19T13:39:45","date_gmt":"2023-05-19T11:39:45","guid":{"rendered":"http:\/\/eafp.uvigo.gal\/gl\/?p=136795"},"modified":"2023-05-19T13:39:45","modified_gmt":"2023-05-19T11:39:45","slug":"a-ii-edicion-dos-premios-etiv-uvigo-a-localizacion-de-videoxogos-convertera-este-venres-a-vigo-na-capital-do-sector","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/a-ii-edicion-dos-premios-etiv-uvigo-a-localizacion-de-videoxogos-convertera-este-venres-a-vigo-na-capital-do-sector\/","title":{"rendered":"A II edici\u00f3n dos Premios ETIV-UVigo \u00e1 localizaci\u00f3n de videoxogos converter\u00e1 este venres a Vigo na capital do sector"},"content":{"rendered":"<h3>Entregaranse sete galard\u00f3ns \u00e1s mellores traduci\u00f3ns realizadas no 2022<\/h3>\n<p>\u201cUn encontro especial no que se reco\u00f1ecer\u00e1 o traballo e o talento dos profesionais dedicados \u00e1 localizaci\u00f3n dos videoxogos\u201d. As\u00ed ser\u00e1 segundo os seus impulsores a cerimonia de entrega de galard\u00f3ns da\u00a0<a href=\"https:\/\/premios.etiv.webs.uvigo.es\/gl\/\">II edici\u00f3n dos Premios ETIV-UVigo \u00e1 localizaci\u00f3n de videoxogos<\/a>, un acto que, por segundo ano consecutivo, volver\u00e1 converter a Vigo en capital da industria do entretemento dixital, en xeral, e, m\u00e1is concretamente, do \u00e1mbito profesional da localizaci\u00f3n de videoxogos, a adaptaci\u00f3n de cada un dos xogos a unha lingua e cultura determinada. Ser\u00e1 ma\u00f1\u00e1 venres \u00e1s 17.00 horas no edificio Redeiras, coa asistencia, entre outras autoridades, do reitor, Manuel Reigosa; o alcalde de Vigo, Abel Caballero, e o decano da Facultade de Filolox\u00eda e Traduci\u00f3n, Jos\u00e9 Montero.<\/p>\n<p>Entregaranse galard\u00f3ns en sete categor\u00edas: mellor localizaci\u00f3n de videoxogo sen dobraxe, mellor localizaci\u00f3n de videoxogo con dobraxe, videoxogo m\u00e1is accesible e mellor localizaci\u00f3n de videxogo en galego, catal\u00e1n e \u00e9uscaro. \u201cCada ano entran a concurso todos os videoxogos lanzados durante o ano natural anterior, neste caso o 2022. Primeiro faise unha fase de votaci\u00f3n p\u00fablica na que a xente pode votar os seus traballos favoritos. De a\u00ed saen dez nominados por categor\u00eda que, na segunda fase, un xurado composto por alumnado do ETIV reduce a tres finalistas\u201d, explica Emmanuel Bourgoin, codirector, xunto con \u00d3scar Ferreiro, Ram\u00f3n M\u00e9ndez e Jos\u00e9 Yuste do T\u00edtulo propio de Especialista en Traduci\u00f3n para a Industria do Videoxogo, ETIV, e equipo impulsor&#8230;<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.uvigo.gal\/universidade\/comunicacion\/duvi\/ii-edicion-premios-etiv-uvigo-localizacion-videoxogos-convertera-venres-vigo-capital-sector\" target=\"_blank\" rel=\"noopener noreferrer\">Ler a nova completa no DUVI.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entregaranse sete galard\u00f3ns \u00e1s mellores traduci\u00f3ns realizadas no 2022 \u201cUn encontro especial no que se reco\u00f1ecer\u00e1 o traballo e o talento dos profesionais dedicados \u00e1 &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/a-ii-edicion-dos-premios-etiv-uvigo-a-localizacion-de-videoxogos-convertera-este-venres-a-vigo-na-capital-do-sector\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":13,"featured_media":136796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[175,209,217,181,216,177,178],"class_list":["post-136795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi","tag-etiv","tag-filoloxia","tag-localizacion-de-videoxogos","tag-premios-etiv","tag-redeiras","tag-traducion","tag-videoxogos"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/136795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=136795"}],"version-history":[{"count":1,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/136795\/revisions"}],"predecessor-version":[{"id":136799,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/136795\/revisions\/136799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/136796"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=136795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=136795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=136795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}