
{"id":238455,"date":"2025-03-15T11:09:24","date_gmt":"2025-03-15T10:09:24","guid":{"rendered":"https:\/\/cpfp.uvigo.gal\/gl\/?p=238455"},"modified":"2025-04-11T11:10:47","modified_gmt":"2025-04-11T09:10:47","slug":"becas-santander-microcredenciales-2025-1a-edicion","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/becas-santander-microcredenciales-2025-1a-edicion\/","title":{"rendered":"Becas Santander \u2013 Microcredenciales 2025, 1\u00aa edici\u00f3n"},"content":{"rendered":"<p>O Santander &#8211; Open Academy lanza unha convocatoria de bolsas onde poder\u00e1s optar a bolsas de 300 euros para a t\u00faa formaci\u00f3n, o programa \u201cBecas Santander \u2013 Microcredenciales 2025, 1\u00aa edici\u00f3n\u201d. E no Centro de Posgrao e Formaci\u00f3n Permanente lanzamos d\u00faas microcredenciais de 5 ECTS inscritas nesta primeira convocatoria.<\/p>\n<p>\ud83d\udd38 <a href=\"https:\/\/cpfp.uvigo.gal\/gl\/estudos\/titulos-propios\/id1172-1\/\" target=\"_blank\" rel=\"noopener\">Excel Avanzado e An\u00e1lise de Datos: Dos Fundamentos \u00e1 Integraci\u00f3n con Power BI<\/a><br \/>\n\ud83d\udd38 <a href=\"https:\/\/cpfp.uvigo.gal\/gl\/estudos\/titulos-propios\/id1173-1\/\" target=\"_blank\" rel=\"noopener\">Visualizaci\u00f3ns interactivas de datos en Power BI<\/a><\/p>\n<p>Que son as microcredenciais?<\/p>\n<p>As microcredenciais son formaci\u00f3ns de curta duraci\u00f3n, focalizadas na adquisici\u00f3n de co\u00f1ecementos, habilidades ou competencias espec\u00edficas. A vantaxe destas microcredenciais \u00e9 que est\u00e1n abertas a todas as persoas, con ou sen titulaci\u00f3n universitaria, e que contan cunha certificaci\u00f3n dixital verificable en todo o mundo. Ademais, permiten unha estrutura modular da formaci\u00f3n e poden acumularse e combinarse en credenciais m\u00e1is amplas, no marco dun itinerario formativo personalizado.<\/p>\n<p>Tes m\u00e1is informaci\u00f3n premento enriba das titulaci\u00f3ns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Santander &#8211; Open Academy lanza unha convocatoria de bolsas onde poder\u00e1s optar a bolsas de 300 euros para a t\u00faa formaci\u00f3n, o programa \u201cBecas &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/becas-santander-microcredenciales-2025-1a-edicion\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":13,"featured_media":238456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[248,251,250,249],"class_list":["post-238455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi","tag-bolsa","tag-microcredenciais","tag-openacademy","tag-santander"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/238455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=238455"}],"version-history":[{"count":0,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/238455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/238456"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=238455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=238455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=238455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}