
{"id":308460,"date":"2026-06-30T14:31:54","date_gmt":"2026-06-30T12:31:54","guid":{"rendered":"https:\/\/cpfp.uvigo.gal\/gl\/?p=308460"},"modified":"2026-06-30T14:31:54","modified_gmt":"2026-06-30T12:31:54","slug":"clausurada-a-2a-edicion-do-curso-de-experto-en-desenvolvemento-de-dispositivos-de-fotonica-integrada","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/clausurada-a-2a-edicion-do-curso-de-experto-en-desenvolvemento-de-dispositivos-de-fotonica-integrada\/","title":{"rendered":"Clausurada a 2\u00aa edici\u00f3n do Curso de Experto en Desenvolvemento de Dispositivos de Fot\u00f3nica Integrada"},"content":{"rendered":"<h3>Culminou coa entrega ao alumnado dos chips que eles mesmos dese\u00f1aron<\/h3>\n<p>Unha vintena de estudantes completaron recentemente a 2\u00aa edici\u00f3n do Curso de Experto en Desenvolvemento de Dispositivos de Fot\u00f3nica Integrada, xestionado academicamente a trav\u00e9s do Centro de Posgrao e Formaci\u00f3n Permanente da UVigo e desenvolvido ao abeiro da C\u00e1tedra NextChip. Marcado pola transformaci\u00f3n do programa formativo cara un modelo baseado en catro microcredenciais independentes que abranguen distintas \u00e1reas clave da fot\u00f3nica, o novo formato permitiu ofrecer unha formaci\u00f3n m\u00e1is flexible e especializada, ali\u00f1ada coas iniciativas europeas de aprendizaxe permanente e orientada a facilitar a adquisici\u00f3n progresiva de competencias avanzadas no sector.<\/p>\n<p>O programa combinou formaci\u00f3n te\u00f3rica e pr\u00e1ctica, achegando \u00e1s persoas participantes as metodolox\u00edas e procesos utilizados na actualidade pola industria internacional, unha aproximaci\u00f3n aplicada que permitiu ao alumnado participar en todas as etapas do desenvolvemento dun circu\u00edto fot\u00f3nico integrado. A formaci\u00f3n, que contou con financiamento da Secretaria de Estado de Telecomunicaciones e Infraestruturas Digitales del Ministerio para&#8230;<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.uvigo.gal\/universidade\/comunicacion\/duvi\/clausurada-2a-edicion-curso-experto-desenvolvemento-dispositivos-fotonica-integrada\">Ler a nova completa no DUVI\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culminou coa entrega ao alumnado dos chips que eles mesmos dese\u00f1aron Unha vintena de estudantes completaron recentemente a 2\u00aa edici\u00f3n do Curso de Experto en &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/clausurada-a-2a-edicion-do-curso-de-experto-en-desenvolvemento-de-dispositivos-de-fotonica-integrada\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":13,"featured_media":308461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-308460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/308460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=308460"}],"version-history":[{"count":1,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/308460\/revisions"}],"predecessor-version":[{"id":308464,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/308460\/revisions\/308464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/308461"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=308460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=308460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=308460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}