
{"id":49957,"date":"2021-04-06T10:00:41","date_gmt":"2021-04-06T08:00:41","guid":{"rendered":"http:\/\/eafp.uvigo.gal\/gl\/?p=49957"},"modified":"2021-05-10T21:36:54","modified_gmt":"2021-05-10T19:36:54","slug":"enxeneria-industrial-oferta-catro-obradoiros-practicos-dirixidos-a-reforzar-as-competencias-dixitais-do-seu-alumnado","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/enxeneria-industrial-oferta-catro-obradoiros-practicos-dirixidos-a-reforzar-as-competencias-dixitais-do-seu-alumnado\/","title":{"rendered":"Enxe\u00f1er\u00eda Industrial oferta catro obradoiros pr\u00e1cticos dirixidos a reforzar as competencias dixitais do seu alumnado"},"content":{"rendered":"<p>Volven os obradoiros de formaci\u00f3n complementaria \u00e1 Escola de Enxe\u00f1er\u00eda Industrial. Coa intenci\u00f3n de achegar ferramentas e recursos inform\u00e1ticos \u00fatiles no eido profesional a alumnado e persoas tituladas, a escola planifica para os meses de xu\u00f1o e xullo catro cursos presenciais sobre os programas SolidWorks, Ansys e Excel. Ignacio Armesto, organizador dos obradoiros e profesor do Departamento de Enxe\u00f1ar\u00eda de Sistemas e Autom\u00e1tica, sinala que estas formaci\u00f3ns serven tanto para mellorar as capacidades do estudantado como para incrementar as competencias dixitais de graduadas e graduados que xa se atopan traballando.<\/p>\n<p>Nesta li\u00f1a, Armesto comenta que esta oferta formativa \u201cnace a petici\u00f3n do alumnado, que bota en falta a posibilidade de afondar no co\u00f1ecemento pr\u00e1ctico dalgunhas tecnolox\u00edas ou ferramentas moi empregadas no \u00e1mbito profesional da s\u00faa especialidade\u201d. Incidindo nestas relaci\u00f3ns co estudantado, o docente anima aos alumnos e alumnas a comunicar as carencias formativas que atopen, \u201cpois as\u00ed naceron moitos dos cursos realizados nos \u00faltimos 10 anos: Catia, Cype, Python, iOS, Android, Arduino, Impresi\u00f3n 3D, etc.\u201d. <\/p>\n<p><a href=\"https:\/\/www.uvigo.gal\/universidade\/comunicacion\/duvi\/enxeneria-industrial-oferta-catro-obradoiros-practicos-dirixidos-reforzar-competencias-dixitais-seu\" target=\"_blank\" rel=\"noopener noreferrer\">Ler a noticia completa no DUVI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volven os obradoiros de formaci\u00f3n complementaria \u00e1 Escola de Enxe\u00f1er\u00eda Industrial. Coa intenci\u00f3n de achegar ferramentas e recursos inform\u00e1ticos \u00fatiles no eido profesional a alumnado &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/enxeneria-industrial-oferta-catro-obradoiros-practicos-dirixidos-a-reforzar-as-competencias-dixitais-do-seu-alumnado\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":2,"featured_media":49958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-49957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/49957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=49957"}],"version-history":[{"count":1,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/49957\/revisions"}],"predecessor-version":[{"id":49961,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/49957\/revisions\/49961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/49958"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=49957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=49957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=49957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}