
{"id":64176,"date":"2021-05-31T10:00:58","date_gmt":"2021-05-31T08:00:58","guid":{"rendered":"http:\/\/eafp.uvigo.gal\/gl\/?p=64176"},"modified":"2021-06-01T16:37:45","modified_gmt":"2021-06-01T14:37:45","slug":"as-redeiras-dan-acubillo-desde-hoxe-a-nova-sede-da-uvigo-no-corazon-da-cidade","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/es\/as-redeiras-dan-acubillo-desde-hoxe-a-nova-sede-da-uvigo-no-corazon-da-cidade\/","title":{"rendered":"As Redeiras dan acubillo desde hoxe \u00e1 nova sede da UVigo no coraz\u00f3n da cidade"},"content":{"rendered":"<p>Unha parte do que orixinalmente foi unha praia entre d\u00faas puntas rochosas e na que desde o s\u00e9culo XII est\u00e1n documentados asentamentos de poboaci\u00f3n, dedicada a actividades relacionadas co mar, acolle desde hoxe a nova sede institucional na cidade de Vigo da Universidade. Catro anos e medio de traballos de rehabilitaci\u00f3n e construci\u00f3n dirixidos polo estudo de arquitectura Abalo Alonso e tres mill\u00f3ns de euros investidos pola Xunta de Galicia en tres pequenas vivendas de pescadores, situadas nos n\u00fameros 11,13 e 15 da praza do Berb\u00e9s, permiten \u00e1 UVigo dispor dun inmoble, no que desenvolver actividades acad\u00e9micas e institucionais no centro da cidade, onde quedara sen presenza, tras abandonar o edificio da antiga Reitor\u00eda da r\u00faa Porto. Redeiras \u00e9 o nome co que a instituci\u00f3n acad\u00e9mica acordou denominar a s\u00faa nova sede e co que quere dar visibilidade ao traballo desenvolvido por este colectivo profesional totalmente feminizado e que, xunto a escabicheiras, regateiras e vendedoras de peixe, poboaron durante s\u00e9culos a paisaxe do Berb\u00e9s, facendo posible co seu labor, non s\u00f3 o desenvolvemento da zona, sen\u00f3n o de toda a cidade de Vigo. <\/p>\n<p>Logo do inicio das obras en decembro de 2016, este luns tivo lugar a inauguraci\u00f3n do inmoble, presidida polo titular do goberno galego, Alberto N\u00fa\u00f1ez Feij\u00f3o; o alcalde de Vigo, Abel Caballero e o reitor da Universidade de Vigo, Manuel Reigosa. No acto de inauguraci\u00f3n, ao que ademais do equipo de goberno da Universidade, asistiron diversas autoridades en representaci\u00f3n dos gobernos auton\u00f3mico e local, ademais de representantes doutras instituci\u00f3ns, o presidente da Xunta asegurou que \u201co edificio que hoxe entregamos \u00e1 UVigo \u00e9 un forma de acreditar un modelo de goberno, que \u00e9 intentar ser \u00fatil \u00e1 sociedade\u201d, recuperando un edificio singular, nun lugar emblem\u00e1tico, \u201conde naceu a cidade de Vigo\u201d. N\u00fa\u00f1ez Feij\u00f3o lembrou que o inmoble localizado nos n\u00fameros 11,13 e 15 da praza do Berb\u00e9s, ocupa unha superficie de 1450 metros cadrados e nel se investiron m\u00e1is de 2 mill\u00f3ns de euros na obra, aos que suma algo m\u00e1is dun mill\u00f3n do custo dos tres edificios, que agora conforman a sede institucional. \u201cSon 3 mill\u00f3ns de euros que van incrementar de xeito exponencial a imaxe de Vigo, a accesibilidade da ensinanza universitaria e o patrimonio das instituci\u00f3ns, neste caso o patrimonio da UVigo\u201d, dixo o presidente da Xunta, que gabou o traballo desenvolvido polo estudo de arquitectura Abalo e Alonso, \u201cuns excelentes arquitectos\u201d, cuxo traballo nesta sede foi recentemente escollido como unha das 70 rehabilitaci\u00f3ns finalistas na Bienal Espa\u00f1ola de Arquitectura y Urbanismo. Feij\u00f3o, para quen esta sede \u00e9 un exemplo de colaboraci\u00f3n institucional, tam\u00e9n destacou a sostenibilidade do inmoble, cunha reduci\u00f3n de emisi\u00f3ns de CO2 \u201ce unha completa sinerx\u00eda coa aerotermia, que \u00e9 unha forma barata de produci\u00f3n fr\u00edo e calor nas r\u00edas, dado que as diferenzas de temperatura non son bruscas\u201d, explicou.<\/p>\n<p><a href=\"https:\/\/www.uvigo.gal\/universidade\/comunicacion\/duvi\/redeiras-dan-acubillo-hoxe-nova-sede-uvigo-corazon-cidade\" target=\"_blank\" rel=\"noopener noreferrer\">Ler a noticia completa no DUVI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unha parte do que orixinalmente foi unha praia entre d\u00faas puntas rochosas e na que desde o s\u00e9culo XII est\u00e1n documentados asentamentos de poboaci\u00f3n, dedicada &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/es\/as-redeiras-dan-acubillo-desde-hoxe-a-nova-sede-da-uvigo-no-corazon-da-cidade\/\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":2,"featured_media":64177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-64176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duvi"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/64176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/comments?post=64176"}],"version-history":[{"count":1,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/64176\/revisions"}],"predecessor-version":[{"id":64180,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/posts\/64176\/revisions\/64180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/64177"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=64176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/categories?post=64176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/tags?post=64176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}