
{"id":310848,"date":"2024-09-06T10:48:45","date_gmt":"2024-09-06T08:48:45","guid":{"rendered":"https:\/\/cpfp.uvigo.gal\/estudos\/titulos-propios\/id1127-1-2\/"},"modified":"2026-07-28T09:09:19","modified_gmt":"2026-07-28T07:09:19","slug":"id1127-1","status":"publish","type":"sigma_course","link":"https:\/\/cpfp.uvigo.gal\/es\/estudios\/titulos-propios\/id1127-1\/","title":{"rendered":"Tecnolog\u00edas aplicadas a las enfermedades respiratorias"},"content":{"rendered":"<div class=\"entry-thumbnail\">\n<p><img decoding=\"async\" src=\"https:\/\/cpfp.uvigo.gal\/wp-content\/plugins\/uvigo-sigma-courses\/public\/images\/1127-1.jpg\" alt=\"Tecnolog\u00edas aplicadas a las enfermedades respiratorias\" class=\"img-fluid\"><\/p>\n<\/div>\n<div class=\"row\">\n<div class=\"col-lg-12\">\n<h3>Experto<\/h3>\n<p class=\"header-list\">\u00c1mbito: Medicina e odontolox\u00eda<span class=\"pull-right\">C\u00f3digo: TCS:1127\/1<\/span><br \/>\n\t\t\u00c1rea de inter\u00e9s principal: Ciencias da sa\u00fade | \u00c1rea de inter\u00e9s secundaria: Ciencias da sa\u00fade<\/p>\n<div class=\"custom-block graylight\">\n<div class=\"row\">\n<div class=\"col lg-4\">\n<h3>Inicio y fin<\/h3>\n<p><i class=\"fa fa-calendar\"><\/i> 16\/09\/2024 &#8211; 31\/05\/2025 <\/p>\n<\/p><\/div>\n<div class=\"col lg-3\">\n<h3>Modalidad<\/h3>\n<p>\t\t\t\t\t\t<i class=\"fa fa-user\" aria-hidden=\"true\"><\/i> Presencial\t\t\t\t<\/div>\n<div class=\"col lg-2\">\n<h3>Cr\u00e9ditos ECTS<\/h3>\n<p><i class=\"fa fa-shield\"><\/i> 20.0 ECTS<\/p>\n<\/p><\/div>\n<div class=\"col lg-3\">\n<h3>Estado<\/h3>\n<p><i class=\"fa fa-cogs\" aria-hidden=\"true\"><\/i> Finalizado\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"mb-2\"><a class=\"btn btn-outline-primary disabled\" style=\"text-transform:none!important\" href=\"xxxx\" target=\"_blank\">30 plazas<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2>Descripci\u00f3n<\/h2>\n<p>La prevalencia de las enfermedades respiratorias (ER) tanto agudas como cr\u00f3nicas se haincrementado de forma destacable en los \u00faltimos a\u00f1os, impactando en gran manera a nivel de la sociedad y los sistemas sanitarios. Su atenci\u00f3n requiere una atenci\u00f3n personalizada, continuada y coordinada entre los distintos niveles y profesionales adem\u00e1s del empoderamiento del paciente y su entorno en sus cuidados. La mayor\u00eda de los pacientes con ER requieren pruebas diagn\u00f3sticas de diferente complejidad en las que participan profesionales de diferentes disciplinas y nuevos procedimientos para el tratamiento, incluyendo aquellos utilizados de forma cr\u00f3nica a nivel domiciliario y con dispositivos cada m\u00e1s sofisticados.Las pruebas necesarias para la adecuada evaluaci\u00f3n de la funci\u00f3n pulmonar o los estudios de imagen tor\u00e1cica o endobronquial, el estudio de los trastornos respiratorios del sue\u00f1o o el uso de terapias por v\u00eda inhalatoria o el soporte ventilatorio son campos en continua innovaci\u00f3n y de aplicaci\u00f3n cada vez a m\u00e1s personas en nuestro entorno. El adecuado conocimiento de las diferentes facetas (indicaciones, realizaci\u00f3n e interpretaci\u00f3n, fundamentos tecnol\u00f3gicos y limitaciones) de todas estas t\u00e9cnicas y el aparataje necesario para llevarlo a cabo son esenciales para garantizar una atenci\u00f3n sanitaria de calidad y poder hacer propuestas para su correcta utilizaci\u00f3n en nuestro entorno, as\u00ed como proponer y desarrollar mejoras que permitan optimizarlas.<\/p>\n<p>Adem\u00e1s, la aplicaci\u00f3n generalizada de otras innovaciones tecnol\u00f3gicas a los procesos cl\u00ednicos y asistenciales incluyendo la telemonitorizaci\u00f3n y el avance de tecnolog\u00edas como el big data o la inteligencia artificial, protagonizar\u00e1n la evoluci\u00f3n del sector sociosanitario en este y otros campos de la salud en los pr\u00f3ximos a\u00f1os. La salud digital puede aportar soluciones para mejorar el autocuidado y la prevenci\u00f3n, el diagn\u00f3stico, el tratamiento, el seguimiento y gesti\u00f3n de los pacientes, especialmente aquellos con enfermedades cr\u00f3nicas, como son muchas de las enfermedades respiratorias, incrementando su autonom\u00eda y calidad de vida y pudiendo mejorar la eficacia y eficiencia del sistema sanitario.Hasta el momento pr\u00e1cticamente no existen programas de formaci\u00f3n que aborden con una visi\u00f3nglobal (procedimiento y equipamiento), integral y pr\u00e1ctica todas las aplicaciones tecnol\u00f3gicas necesarias para el manejo seguro y eficiente de pacientes con ER, objetivo por lo que la UVigo dise\u00f1a y pone en marcha la presente titulaci\u00f3n, de forma que el profesional que lo supere estar\u00e1 capacitado para realizar y controlar la adecuada utilizaci\u00f3n de estas tecnolog\u00edas as\u00ed como los dispositivos y aparataje necesarios para ello.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-lg-6\">\n<p class=\"header-list\">Director\/a:<\/p>\n<p>Dr. Jos\u00e9 Alberto Fern\u00e1ndez Villar<\/p>\n<p class=\"header-list\">Tel\u00e9fono contacto:<\/p>\n<p>986 130 304<\/p>\n<p class=\"header-list\">Email contacto:<\/p>\n<p>alberto.fernandez.villar@sergas.es<\/p>\n<p class=\"header-list\">Entidad organizadora:<\/p>\n<p>Centro de Posgrao e Formaci\u00f3n Permanente<\/p>\n<\/p><\/div>\n<div class=\"col-lg-6\">\n<div class=\"card\">\n<div class=\"card-body\">\n<p style=\"color:#dc3545\" class=\"header-list\">PER\u00cdODO DE INSCRIPCI\u00d3N<br \/>\n\t\t\t<small>Inscripci\u00f3n cerrada<\/small><br \/>\n\t\t\t03\/06\/2024 &#8211; 12\/09\/2024<\/p>\n<p><\/p>\n<hr \/>\n<p style=\"color:#dc3545\" class=\"header-list\">PER\u00cdODO DE MATR\u00cdCULA<br \/>\n\t\t\t<small>Matr\u00edcula cerrada<\/small><br \/>\n\t\t\t15\/07\/2024 &#8211; 13\/09\/2024<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<p class=\"mb-2\"><a class=\"btn btn-primary btn-icon disabled\" style=\"text-transform:none!important\" href=\"https:\/\/secretaria.uvigo.gal\/uvigo.sv\/index.php?modulo=portalAcademico\" target=\"_blank\" rel=\"noopener noreferrer\">Matr\u00edcula cerrada<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2>Colaboradores<\/h2>\n<div class=\"row\">\n<div class=\"col-sm-12 col-md-12 col-lg-12\" style=\"text-align:center\">\n\t\t\t  \t<a href=\"https:\/\/www.fundacionbiomedica.es\/\"><br \/>\n\t\t\t  \t\t<img decoding=\"async\" style=\"width: 30%;height: auto;object-fit: cover\" src=\"https:\/\/uvigodb.webs8.uvigo.es\/public\/images\/sigma_courses_pictures\/logos\/logo_cmyk.png\" alt=\"Fundaci\u00f3n Biom\u00e9dica Galicia Sur\"><br \/>\n\t\t\t  \t<\/a><\/p>\n<div style=\"text-align: center;color: #202020;font-weight: 300;margin-top: 10px;font-size: 1rem\">\n\t\t\t  \t\t<a href=\"https:\/\/www.fundacionbiomedica.es\/\" target=\"_blank\"><br \/>\n\t\t\t  \t\t\tFundaci\u00f3n Biom\u00e9dica Galicia Sur\t\t\t  \t\t<\/a>\n\t\t\t  \t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>&nbsp;<\/p>\n<h2>Modalidad<\/h2>\n<div class=\"card\">\n<div class=\"row\">\n<div class=\"col lg-6\">\n<div class=\"card-body\">\n<h3 class=\"card-title\">Docencia presencial\/virtual<\/h3>\n<p style=\"color:green\"><i class=\"fa fa-check-square-o fa-3x\" aria-hidden=\"true\"><\/i><\/p>\n<p>198 horas<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col lg-3\">\n<div class=\"card-body\">\n<h3 class=\"card-title\">Docencia no presencial<\/h3>\n<p><i class=\"fa fa-minus fa-3x\" aria-hidden=\"true\"><\/i><\/p>\n<p>0 horas<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col lg-3\">\n<div class=\"card-body\">\n<h3 class=\"card-title\">Pr\u00e1cticas en empresa<\/h3>\n<p><i class=\"fa fa-minus fa-3x\" aria-hidden=\"true\"><\/i><\/p>\n<p>0 horas<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col lg-12\">\n<div class=\"card-body\">\n<p><strong>Lugar de impartici\u00f3n<\/strong><br \/>\nHospital \u00c1lvaro Cunqueiro de Vigo &#8211; Plataforma de teledocencia de la Universidade de Vigo\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2>Horario<\/h2>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Estudios de imagen y t\u00e9cnicas broncopleurales (septiembre-octubre 2024)&nbsp;<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 19, 24, 26 septiembre y 1 octubre de 16,00 a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00edas 15 de octubre de 16,00 h a 21,00 h y 17 de octubre de 16,00 a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana 7 a 11 de octubre horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8 a 15 h entre el 24 de septiembre y 17 de octubre<\/div>\n<div>Examen y revisi\u00f3n de examen: 17 de octubre 19,00 a 21 h<\/div>\n<div><\/div>\n<div>&nbsp;<\/div>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Terapia inhalada y oxigenoterapia (octubre-noviembre 2024)<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 22, 24 y 29 octubre y 5 noviembre de 16,00 a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00edas 19 de noviembre de 16,00 h a 21,00 h y 21 de noviembre de 16,00 h a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana 11 a 15 de noviembre en horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8 a 16 h entre 24 de octubre y 15 de noviembre (un \u00fanico d\u00eda por grupos)<\/div>\n<div>Examen y revisi\u00f3n de examen: 21 de noviembre de 19,00 a 21,00 h<\/div>\n<div>&nbsp;&nbsp;<\/div>\n<div><\/div>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Ventilaci\u00f3n no invasiva (diciembre 2024-enero 2025)&nbsp;<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 3 de diciembre, 10 y 17 de diciembre de 16,00 a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00edas 21 de enero de 16,00 h a 21,00 h y 23 de enero de 16,00 h a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana 13 a 17 de enero en horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8,30 a 14,30 h entre 10 y 20 de diciembre y 13 a 23 de enero (un \u00fanico d\u00eda por grupos)<\/div>\n<div>Examen y revisi\u00f3n de examen: 23 de enero de 19,00 h a 21,00 h<\/div>\n<div><\/div>\n<div>&nbsp;<\/div>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Tecnolog\u00edas aplicadas a los trastornos respiratorios del sue\u00f1o (febrero-marzo 2025)<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 4, 6 y 11 de febrero de 16,00 a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00edas 4 de marzo de 16,00 h a 21,00 h y 6 de marzo de 16,00 h a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana 17 a 21 de febrero en horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8,30 a 14,30 h entre 10 de febrero y 6 de marzo (un \u00fanico d\u00eda por grupos)<\/div>\n<div>Examen y revisi\u00f3n de examen: 6 de marzo de 19,00 h a 21,00 h<\/div>\n<div><\/div>\n<div>&nbsp;<\/div>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>El laboratorio de funci\u00f3n pulmonar (marzo-abril 2025)&nbsp;<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 18, 25, 27 de marzo de 16,00 h a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00edas 22 de abril de 16,00 h a 21,00 h y 24 de abril de 16,00 h a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana 30 marzo a 4 de abril en horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8,30 a 14,30 h entre 24 de marzo y 24 de abril (un \u00fanico d\u00eda por grupos)<\/div>\n<div>Examen y revisi\u00f3n de examen: 24 de abril de 19,00 h a 21,00 h<\/div>\n<div><\/div>\n<div>&nbsp;&nbsp;<\/div>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Salud digital y nuevas tecnolog\u00edas (abril-mayo 2025)<\/li>\n<\/ul>\n<div>Clases te\u00f3ricas e interactivas: D\u00edas 29 de abril, 8 y 13 de mayo de 16,00 a 21,00 h<\/div>\n<div>Exposici\u00f3n trabajos: D\u00eda 27 de mayo de 16,00 h a 21,00 h y 29 de mayo de 16,00 h a 19,00 h<\/div>\n<div>Tutor\u00edas online: Semana del 19 al 23 de mayo en horario de tarde<\/div>\n<div>Pr\u00e1cticas: Horario de 8,30 a 14,30 h entre 5 de mayo y 23 de mayo (un \u00fanico d\u00eda por grupos)<\/div>\n<div>Examen y revisi\u00f3n de examen: 29 de mayo de 19,00 h a 20,00 h<\/div>\n<div><\/div>\n<div>&nbsp;<\/div>\n<div>Examen final: 29 de mayo de 20,00 h a 21,00 h<\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Precios<\/h2>\n<table style=\"margin-left:0px\" cellpadding=\"0\" cellspacing=\"0\">\n<thead>\n<tr>\n<th scope=\"col\" width=\"33%\">P\u00fablico en general<\/th>\n<th scope=\"col\" width=\"33%\">Alumni UVigo<\/th>\n<th scope=\"col\" width=\"34%\">Comunidad UVigo<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>900 \u20ac<\/td>\n<td>810 \u20ac<\/td>\n<td>765 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Observaciones a los precios<\/strong><\/p>\n<p><b>La Fundaci\u00f3n Biom\u00e9dica Galicia Sur subvencionar\u00e1 con ayudas al estudio a todas las personas que superen el t\u00edtulo. La cuant\u00eda de la subvenci\u00f3n ser\u00e1 como m\u00ednimo de 300 euros<\/b><\/p>\n<p>Las personas en situaci\u00f3n de desempleo o discapacidad reconocida podr\u00e1n solicitar el precio reducido de la comunidad universitaria en el momento de la matr\u00edcula<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<h2>Objetivos<\/h2>\n<p>\tFormaci\u00f3n avanzada orientada a desarrollar en su alumnado competencias y habilidades que lespermitan dar respuesta de alto nivel y liderar acciones de mejora en todos los aspectos relacionados con las tecnolog\u00edas diagn\u00f3sticas y terap\u00e9uticas aplicadas a las enfermedades respiratorias.\t<\/p>\n<p>&nbsp;<\/p>\n<h2>Destinatarios<\/h2>\n<p>\tPersonas graduadas o licenciadas en Enfermer\u00eda, Fisioterapia e Ingenier\u00eda Biom\u00e9dica.\t<\/p>\n<p>&nbsp;<\/p>\n<h2>Salidas Profesionales<\/h2>\n<p>Con este t\u00edtulo&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">de experto universitario&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">los\/as estudiantes adquirir\u00e1n una excelente formaci\u00f3n y habilidades en todos los&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">campos tecnol\u00f3gicos relacionados con las enfermedades respiratorias y ser\u00e1n capaces desde varias&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">perspectivas (cl\u00ednica y t\u00e9cnica) de ponerlas en marcha, as\u00ed como de abordar mejoras e innovaciones&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">en este campo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>Competencias Espec\u00edficas<\/h2>\n<ul class=\"list-peak\" style=\"margin-top:10px\">\n<li>Conocer la anatom\u00eda del sistema respiratorio para entender y optimizar las aplicacionestecnol\u00f3gicas necesarias para la adecuada atenci\u00f3n de las enfermedades respiratorias.<\/li>\n<li>Conocer la fisiopatolog\u00eda del sistema respiratorio para entender y optimizar las aplicaciones tecnol\u00f3gicas necesarias para la adecuada atenci\u00f3n de las enfermedades respiratorias.<\/li>\n<li>Identificar las bases tecnol\u00f3gicas de los dispositivos e instrumental que se precisan parael diagn\u00f3stico, tratamiento y seguimiento de las enfermedades respiratorias.<\/li>\n<li>Identificar y describir las indicaciones para la realizaci\u00f3n y la interpretaci\u00f3n de losresultados de las principales pruebas diagn\u00f3sticas y terapias aplicadas a las enfermedadesrespiratorias.<\/li>\n<li>Aplicar los conocimientos te\u00f3ricos y las habilidades pr\u00e1cticas adquiridas en la utilizaci\u00f3nde las t\u00e9cnicas y procedimientos instrumentales relacionados con las enfermedadesrespiratorias acordes a la cartera de servicios sanitarios propia de su formaci\u00f3n.<\/li>\n<li>Reconocer y describir los criterios de calidad y seguridad de las tecnolog\u00edas aplicadas al diagn\u00f3stico y tratamiento de las enfermedades respiratorias en cada contexto cl\u00ednico.<\/li>\n<li>Conocer las limitaciones, riesgos y soluciones de las tecnolog\u00edas aplicadas a lasenfermedades respiratorias.<\/li>\n<li>Disponer de las habilidades y de las competencias necesarias para la b\u00fasqueda de las innovaciones en este campo y liderar proyectos de mejora en los procesos tecnol\u00f3gicos aplicados a las distintas enfermedades del aparato respiratorio.<\/li>\n<li>Conocer el contexto y las estrategias existentes a distintos niveles para el desarrollo de la salud digital aplicada a las enfermedades respiratorias, as\u00ed como los sistemas deinformaci\u00f3n que dan soporte a su actividad.Conocer y aplicar la normativa y regulaci\u00f3n local, auton\u00f3mica, nacional e internacional enel \u00e1mbito de las tecnolog\u00edas aplicadas a las enfermedades respiratorias.<\/li>\n<li>Resolver casos pr\u00e1cticos en el campo de las delas tecnolog\u00edas aplicadas a las enfermedadesrespiratorias, lo que implica la elaboraci\u00f3n previa de material, la identificaci\u00f3n decuestiones problem\u00e1ticas, la selecci\u00f3n, interpretaci\u00f3n y la exposici\u00f3n argumentada de este\u00e1mbito de la salud respiratoria de las personas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Competencias Transversales<\/h2>\n<ul>\n<li style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">Proponer soluciones creativas e innovadoras a situaciones o problemas complejos, propios del \u00e1mbito de conocimiento.<\/li>\n<li style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">Colaborar eficazmente en equipos de trabajo, asumiendo responsabilidades y funciones de liderazgo y contribuyendo a la mejora y desarrollo colectivo.<\/li>\n<li style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">Comunicarse de manera efectiva, tanto de forma oral como escrita, adapt\u00e1ndose a las caracter\u00edsticas de la situaci\u00f3n y de la audiencia.<\/li>\n<li style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">Actuar con autonom\u00eda en el aprendizaje, tomando decisiones fundamentadas en diferentes contextos.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Condiciones de acceso<\/h2>\n<p>Persoas graduadas ou licenciadas en Enfermer\u00eda, Fisioterapia ou Enxe\u00f1er\u00eda Biom\u00e9dica que acrediten:<\/p>\n<p>1. Un t\u00edtulo universitario dentro del EEES que otorgue el acceso a ense\u00f1anzas oficiales de postgrado.<\/p>\n<p>2. Un t\u00edtulo extranjero, ajeno al EEES, homologado a un t\u00edtulo universitario oficial del EEES.<\/p>\n<p>3. Un t\u00edtulo extranjero, ajeno al EEES, no homologado, pero que acredite un nivel equivalente a un t\u00edtulo universitario de grado dentro del EEES que faculte, en el pa\u00eds de expedici\u00f3n del t\u00edtulo, para el acceso a las ense\u00f1anzas de postgrado.<\/p>\n<p>&nbsp;<\/p>\n<p>DOCUMENTACI\u00d3N REQUERIDA:<\/p>\n<p>1) Documento de identidad o pasaporte<\/p>\n<p>2) T\u00edtulo universitario o certificado de estudios<\/p>\n<p>3) Carta de motivaci\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<h2>Criterios de selecci\u00f3n<\/h2>\n<p><p><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">1) Titulaci\u00f3n en Enfermer\u00eda<\/span><\/p>\n<p style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">2) Titulaciones en fisioterapia y en ingenier\u00eda biom\u00e9dica.<\/p>\n<p style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">3) Actividad profesional relacionada con la tem\u00e1tica respiratoria<\/p>\n<p style=\"--tw-translate-x: 0;--tw-translate-y: 0;--tw-rotate: 0;--tw-skew-x: 0;--tw-skew-y: 0;--tw-scale-x: 1;--tw-scale-y: 1;--tw-pan-x:;--tw-pan-y:;--tw-pinch-zoom:;--tw-scroll-snap-strictness: proximity;--tw-ordinal:;--tw-slashed-zero:;--tw-numeric-figure:;--tw-numeric-spacing:;--tw-numeric-fraction:;--tw-ring-inset:;--tw-ring-offset-width: 0px;--tw-ring-offset-color: #fff;--tw-ring-offset-shadow: 0 0 #0000;--tw-ring-shadow: 0 0 #0000;--tw-shadow: 0 0 #0000;--tw-shadow-colored: 0 0 #0000;--tw-blur:;--tw-brightness:;--tw-contrast:;--tw-grayscale:;--tw-hue-rotate:;--tw-invert:;--tw-saturate:;--tw-sepia:;--tw-drop-shadow:;--tw-backdrop-blur:;--tw-backdrop-brightness:;--tw-backdrop-contrast:;--tw-backdrop-grayscale:;--tw-backdrop-hue-rotate:;--tw-backdrop-invert:;--tw-backdrop-opacity:;--tw-backdrop-saturate:;--tw-backdrop-sepia:\">4) Carta de motivaci\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<h2>Asignaturas<\/h2>\n<table style=\"margin-left:0px\" cellpadding=\"0\" cellspacing=\"0\">\n<thead>\n<tr>\n<th scope=\"col\">id<\/th>\n<th scope=\"col\">nombre<\/th>\n<th scope=\"col\">caracter<\/th>\n<th scope=\"col\">cr\u00e9ditos<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>200380<\/td>\n<td>Estudos de imaxe e t\u00e9cnicas broncopleurais<\/td>\n<td>Obligatoria<\/td>\n<td>4.0<\/td>\n<\/tr>\n<tr>\n<td>200381<\/td>\n<td>Terapia inhalada y oxigenoterapia<\/td>\n<td>Obligatoria<\/td>\n<td>4.0<\/td>\n<\/tr>\n<tr>\n<td>200382<\/td>\n<td>Ventilaci\u00f3n no invasiva<\/td>\n<td>Obligatoria<\/td>\n<td>3.0<\/td>\n<\/tr>\n<tr>\n<td>200383<\/td>\n<td>Tecnolog\u00edas aplicadas a los trastornos respiratorios del sue\u00f1o<\/td>\n<td>Obligatoria<\/td>\n<td>3.0<\/td>\n<\/tr>\n<tr>\n<td>200384<\/td>\n<td>El laboratorio de funci\u00f3n pulmonar<\/td>\n<td>Obligatoria<\/td>\n<td>3.0<\/td>\n<\/tr>\n<tr>\n<td>200385<\/td>\n<td>Salud digital y nuevas tecnolog\u00edas<\/td>\n<td>Obligatoria<\/td>\n<td>3.0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2>Profesorado<\/h2>\n<p><div>Jos\u00e9 Alberto Fern\u00e1ndez Villar, Especialista en Neumolog\u00eda<\/div>\n<div>Mar\u00eda Torres Dur\u00e1n Medicina, Especialista en Neumolog\u00eda<\/div>\n<div>Manuel Casal Guisande, Ingeniero Industrial<\/div>\n<div>Xavier Novoa Conde, Ingeniero&nbsp;Industrial&nbsp;<\/div>\n<div>Rodrigo Varela Gestoso, Inform\u00e1tico&nbsp;<\/div>\n<div>In\u00e9s De Castro, Doctora en Ingenier\u00eda de Sistemas&nbsp;<\/div>\n<div>Cristina Represas Represas, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Virginia Leiro Fern\u00e1ndez, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Mar\u00eda P\u00e9rez Costas, Especialista en Radiodiagn\u00f3stico<\/div>\n<div>Alba L\u00f3pez Castell\u00f3, Especialista en Radiodiagn\u00f3stico<\/div>\n<div>In\u00e9s Dom\u00ednguez Pardo, Especialista en Medicina Nuclear<\/div>\n<div>Alberto Fern\u00e1ndez Garc\u00eda, Enfermeiro Radiolog\u00eda Intervencionista<\/div>\n<div>Mercedes Cu\u00f1a Delgado, Enfermera Servicio de Neumolog\u00eda<\/div>\n<div>Manuel N\u00fa\u00f1ez Delgado, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Cristina Pou \u00c1lvarez, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Tamara Lourido Cebreiro, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Ana Priegue Carrea,&nbsp; Enfermera Servicio&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Daniel Ferreiro Carballal, Fisioterapeuta<\/div>\n<div>Paula Riveiro Villaverde, Enfermera Servicio&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Mar Mosteiro A\u00f1\u00f3n, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Mar\u00eda Jos\u00e9 Mu\u00f1oz Mart\u00ednez, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Sonia Fern\u00e1ndez Gil, Especialista en Neurofisiolog\u00eda Cl\u00ednica<\/div>\n<div>Almudena Gonz\u00e1lez Montaos, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Lara Br\u00e1nd\u00f3n Guerreiro,&nbsp; Enfermera<\/div>\n<div>M Ang\u00e9lica Gonz\u00e1lez Italiani, Enfermera<\/div>\n<div>Cristina Ramos Hern\u00e1ndez, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Marta N\u00fa\u00f1ez Fern\u00e1ndez, Especialista en&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Luz Cerdeira Dom\u00ednguez, Enfermera Servizo&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Paula Dom\u00ednguez P\u00e9rez, Enfermera Servizo&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Neumolog\u00eda<\/span><\/div>\n<div>Daniel Sim\u00f3n Valero, Enfermero Innovaci\u00f3n<\/div>\n<div>Paz Gonz\u00e1lez De la Fuente, Ingeniera de Telecomunicaci\u00f3n<\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<h2>Evaluaci\u00f3n<\/h2>\n<p><div>Evaluaci\u00f3n continuada por medio de observaci\u00f3n, trabajos individuales y en grupo, controles escritos,&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">participaci\u00f3n en aula o campus virtual, tutor\u00edas.<\/span><\/div>\n<div>Asistencia y participaci\u00f3n.<\/div>\n<div>Pruebas: examen de cada materia y examen final.<\/div>\n<div>Se podr\u00e1 superar el curso aprobando todas las materias (m\u00e1s) de un 50% de la evaluaci\u00f3n de conocimientos&nbsp;<span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">te\u00f3ricos. La asistencia a las clases presenciales deber\u00e1 ser superior al 80%, se deben de realizar todas las&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">presentaciones incluidas en el programa y la asistencia a las pr\u00e1cticas ser\u00e1 del 90%.&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">Si no se alcanza el 50% en alguna de las materias te\u00f3ricas podr\u00e1 presentarse a la evaluaci\u00f3n final solo con las&nbsp;<\/span><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\">materias no superadas.<\/span><\/div>\n<div><span style=\"color: var(--bs-body-color);font-size: var(--bs-body-font-size);text-align: var(--bs-body-text-align)\"><br \/><\/span><\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<h2>Titulaci\u00f3n<\/h2>\n<p>T\u00edtulo de Experto Universitario en tecnolog\u00edas aplicadas a las enfermedades respiratorias<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_monsterinsights_skip_tracking":false},"class_list":["post-310848","sigma_course","type-sigma_course","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/sigma_course\/310848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/sigma_course"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/sigma_course"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=310848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}