
{"id":298529,"date":"2026-04-13T14:10:32","date_gmt":"2026-04-13T12:10:32","guid":{"rendered":"https:\/\/cpfp.uvigo.gal\/gl\/?p=298529"},"modified":"2026-04-16T09:48:03","modified_gmt":"2026-04-16T07:48:03","slug":"nova-convocatoria-de-bolsas-santander-open-academy","status":"publish","type":"post","link":"https:\/\/cpfp.uvigo.gal\/gl\/nova-convocatoria-de-bolsas-santander-open-academy\/","title":{"rendered":"Nova convocatoria de bolsas Santander Open Academy"},"content":{"rendered":"<p>Volve o programa &#8220;Becas Santander \u2013 Microcredenciales 2026, 1\u00aa edici\u00f3n\u201d onde poder\u00e1s optar a unha das bolsas de 300 euros do Santander &#8211; Open Academy para a microcredencial<span style=\"font-size: 1rem;\">\ud83d\udd38\u00a0<\/span><a style=\"font-size: 1rem; background-color: #ffffff;\" href=\"https:\/\/cpfp.uvigo.gal\/gl\/estudos\/titulos-propios\/id1172-3\/\" target=\"_blank\" rel=\"noopener\">Excel Avanzado e An\u00e1lise de Datos: Dos Fundamentos \u00e1 Integraci\u00f3n con Power BI \ud83d\udd38<\/a><\/p>\n<p>A convocatoria de bolsas ser\u00e1 xestionada pola Universidade de Vigo e ser\u00e1 publicada nos pr\u00f3ximos d\u00edas.<\/p>\n<p>Lembra que para ter dereito \u00e1 bolsa, ser\u00e1 requisito indispensable preinscribirse na nosa web no curso e darse de alta en prazo na plataforma <a href=\"https:\/\/app.santanderopenacademy.com\/es\/program\/microcredenciales-2026-i-edicion?utm_source=Universidad&amp;utm_medium=Referral&amp;utm_campaign=Microcredenciales1_Espana_Unis\">Santander Open Academy<\/a> seleccionando o curso e a Universidade de Vigo.<\/p>\n<p>\u00c9 dicir:<\/p>\n<ol>\n<li>Preinscribirse no curso. Lembra que a preinscrici\u00f3n pecha o 20 de maio.<\/li>\n<li>Inscribirse na web do <a href=\"https:\/\/app.santanderopenacademy.com\/es\/program\/microcredenciales-2026-i-edicion?utm_source=Universidad&amp;utm_medium=Referral&amp;utm_campaign=Microcredenciales1_Espana_Unis\">Santander Open Academy<\/a> e solicitar a bolsa no curso correspondente ATA O 20 DE MAIO<\/li>\n<li>Agardar a que est\u00e9s admitido\/a e matricularse na nosa web na <a href=\"https:\/\/cpfp.uvigo.gal\/gl\/estudos\/titulos-propios\/id1172-3\/\">microcredencial<\/a> lembr\u00e1ndose de seleccionar no \u00faltimo paso da matr\u00edcula &#8220;aplicar descontos&#8221; e &#8220;Bolsa Santander Formaci\u00f3n Permanente&#8221;.<\/li>\n<\/ol>\n<p>Aqueles\/as que non se inscribiran na web do Santander Open Academy antes do 20 de maio non poder\u00e1n solicitar a bolsa. A obtenci\u00f3n da bolsa queda supeditada \u00e1 asistir como m\u00ednimo ao 80% da docencia do curso.<\/p>\n<p><i class=\"fa fa-file-pdf-o\" style=\"margin-top: 20px;\"><\/i><a href=\"https:\/\/secretaria.uvigo.gal\/uv\/web\/convocatoria\/public\/show\/1832\">\u00a0Convocatoria<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volve o programa &#8220;Becas Santander \u2013 Microcredenciales 2026, 1\u00aa edici\u00f3n\u201d onde poder\u00e1s optar a unha das bolsas de 300 euros do Santander &#8211; Open Academy &hellip; <a class=\"excerpt_more\" href=\"https:\/\/cpfp.uvigo.gal\/gl\/nova-convocatoria-de-bolsas-santander-open-academy\/\">Continuar<\/a><\/p>\n","protected":false},"author":13,"featured_media":298530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[274],"tags":[],"class_list":["post-298529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-microcredenciais"],"_links":{"self":[{"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/posts\/298529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/comments?post=298529"}],"version-history":[{"count":10,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/posts\/298529\/revisions"}],"predecessor-version":[{"id":298612,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/posts\/298529\/revisions\/298612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/media\/298530"}],"wp:attachment":[{"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/media?parent=298529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/categories?post=298529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpfp.uvigo.gal\/gl\/wp-json\/wp\/v2\/tags?post=298529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}